{"id":2714,"date":"2023-02-16T09:01:35","date_gmt":"2023-02-16T09:01:35","guid":{"rendered":"https:\/\/jinsuncarbon.com\/?p=2714"},"modified":"2025-01-01T02:07:00","modified_gmt":"2025-01-01T02:07:00","slug":"uso-e-preco-da-sucata-de-anodo-de-carbono","status":"publish","type":"post","link":"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/","title":{"rendered":"Usos e pre\u00e7os da sucata de \u00e2nodo de carbono"},"content":{"rendered":"<p>A sucata de \u00e2nodo de carbono \u00e9 um subproduto valioso, mas frequentemente ignorado, da produ\u00e7\u00e3o de alum\u00ednio. Refere-se \u00e0 parte residual depois que o bloco de carbono do \u00e2nodo pr\u00e9-cozido \u00e9 usado na c\u00e9lula eletrol\u00edtica. Ao reciclar essa sucata, as empresas podem ajudar a reduzir seu impacto ambiental e aproveitar os poss\u00edveis benef\u00edcios. Este artigo discute os usos, os pre\u00e7os e os benef\u00edcios da reciclagem.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/#What_is_carbon_anode_scrap\" >O que \u00e9 sucata de \u00e2nodo de carbono?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/#Carbon_anode_scrap_use\" >Uso de sucata de \u00e2nodo de carbono.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/#Carbon_Anode_Scraps_Prices\" >Pre\u00e7os das sucatas de \u00e2nodo de carbono.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/#Applications_and_Benefits\" >Aplicativos e benef\u00edcios:<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/#a_Recycling_and_Reuse\" >a. Reciclagem e reutiliza\u00e7\u00e3o:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/#b_Environmental_Sustainability\" >b. Sustentabilidade ambiental:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/#Steps_Involved_in_Recycling\" >Etapas envolvidas na reciclagem.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/#Conclusion\" >Conclus\u00e3o<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"What_is_carbon_anode_scrap\"><\/span>O que \u00e9 sucata de \u00e2nodo de carbono?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/jinsuncarbon.com\/pt\/\/anode-carbon-block\/\">\u00c2nodos de carbono<\/a> conduzem eletricidade na c\u00e9lula eletrol\u00edtica e participam da rea\u00e7\u00e3o do \u00e2nodo, portanto s\u00e3o constantemente consumidos, e a sucata de \u00e2nodo de carbono \u00e9 o resultado desse processo.<\/p>\n<p>\u00c9 um subproduto da produ\u00e7\u00e3o de alum\u00ednio quando a mat\u00e9ria-prima \u00e9 derretida e transformada em produto acabado. O \u00e2nodo residual \u00e9 geralmente 15-25% da quantidade de bloco de carbono do \u00e2nodo, que pode ser reciclado.<\/p>\n<p>Os fabricantes dividem a sucata em sucata de \u00e2nodo de carbono duro e macio. Os duros funcionam quase t\u00e3o bem quanto os \u00e2nodos. Os macios s\u00e3o visivelmente diferentes, muito oxidados por dentro e por fora.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2740\" src=\"http:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/609.jpg\" alt=\"O uso de \u00e2nodo pr\u00e9-cozido - f\u00e1brica na China\" width=\"501\" height=\"293\" srcset=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/609.jpg 550w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/609-300x176.jpg 300w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Carbon_anode_scrap_use\"><\/span>Uso de sucata de \u00e2nodo de carbono.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Tem uma variedade de usos na produ\u00e7\u00e3o de alum\u00ednio e em outros setores. Ele \u00e9 quebrado em part\u00edculas m\u00e9dias e grossas ap\u00f3s a remo\u00e7\u00e3o completa do eletr\u00f3lito da superf\u00edcie. Elas podem substituir parte do coque calcinado ou ser usadas como mat\u00e9ria-prima para a dosagem de \u00e2nodo. Al\u00e9m disso, as f\u00e1bricas podem us\u00e1-lo como combust\u00edvel de fundi\u00e7\u00e3o de alto poder calor\u00edfico.<\/p>\n<p>O valor calor\u00edfico da sucata de \u00e2nodo \u00e9 alto, o calor pode chegar a 8.000 calorias e o teor de carbono \u00e9 superior a 97%. O valor de combust\u00e3o de 1 tonelada \u00e9 equivalente a 1,5 tonelada de coque metal\u00fargico.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Carbon_Anode_Scraps_Prices\"><\/span>Pre\u00e7os das sucatas de \u00e2nodo de carbono.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O pre\u00e7o da sucata de \u00e2nodo de carbono depende do tipo e da quantidade de material comprado. Normalmente, o pre\u00e7o depende do tamanho, do peso e da composi\u00e7\u00e3o da sucata. Os pre\u00e7os tamb\u00e9m podem variar dependendo da localiza\u00e7\u00e3o do fornecedor de sucata de \u00e2nodo de carbono e do tipo de sucata adquirida.<\/p>\n<p>Normalmente, custa entre $0,10 e $1,00 por libra. Os pre\u00e7os flutuam de acordo com o mercado, portanto, \u00e9 essencial ficar de olho nos pre\u00e7os atuais antes de comprar.<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Applications_and_Benefits\"><\/span>Aplicativos e benef\u00edcios:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"a_Recycling_and_Reuse\"><\/span>a. Reciclagem e reutiliza\u00e7\u00e3o:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Recupera\u00e7\u00e3o de carbono:<\/strong> A sucata de \u00e2nodo de carbono pode ser reciclada e processada para recuperar materiais de carbono de alta qualidade. Esses materiais podem ser reintroduzidos para produzir novos \u00e2nodos, reduzindo a necessidade de recursos de carbono virgem e minimizando o desperd\u00edcio.<\/p>\n<p><strong>Produtos de carbono:<\/strong> As sucatas de \u00e2nodo de carbono podem ser processadas em v\u00e1rios produtos \u00e0 base de carbono, como eletrodos, refrat\u00e1rios e elevadores de carbono, encontrando aplica\u00e7\u00f5es na fabrica\u00e7\u00e3o de a\u00e7o, <a href=\"https:\/\/www.reliance-foundry.com\/blog\/what-is-a-foundry\" target=\"_blank\" rel=\"noopener\">fundi\u00e7\u00f5es<\/a>e outros setores.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"b_Environmental_Sustainability\"><\/span>b. Sustentabilidade ambiental:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Redu\u00e7\u00e3o de res\u00edduos:<\/strong> A utiliza\u00e7\u00e3o de sucata de \u00e2nodo de carbono reduz os res\u00edduos gerados na <a href=\"https:\/\/www.rsc.org\/periodic-table\/element\/13\/aluminium#:~:text=Aluminium%20is%20a%20silvery%2Dwhite,beer%20kegs%20and%20aeroplane%20parts.\" target=\"_blank\" rel=\"noopener\">alum\u00ednio<\/a> produ\u00e7\u00e3o e setores relacionados. Ele promove uma economia circular, desviando materiais de sucata dos aterros sanit\u00e1rios e diminuindo a demanda por novos recursos de carbono.<\/p>\n<p><strong>Energia e emiss\u00f5es:<\/strong> A reciclagem e a reutiliza\u00e7\u00e3o de sucata de \u00e2nodo de carbono consomem menos recursos energ\u00e9ticos em compara\u00e7\u00e3o com a produ\u00e7\u00e3o de materiais de carbono virgens. Isso leva \u00e0 redu\u00e7\u00e3o das emiss\u00f5es de gases de efeito estufa e a um menor impacto ambiental.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Steps_Involved_in_Recycling\"><\/span>Etapas envolvidas na reciclagem.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A reciclagem de sucata de \u00e2nodo de carbono \u00e9 relativamente f\u00e1cil e envolve v\u00e1rias etapas. Depois de substitu\u00ed-lo pelo eletrolisador, remova a casca dura do eletr\u00f3lito em sua superf\u00edcie. Em seguida, ele \u00e9 separado das garras de a\u00e7o por meio de uma m\u00e1quina ou manualmente. Durante esse processo, os trabalhadores s\u00e3o triturados, peneirados e divididos em diferentes tamanhos de part\u00edculas.<\/p>\n<p>Os trabalhadores devem limpar a sucata do \u00e2nodo com cuidado, pois o eletr\u00f3lito preso \u00e0 sua superf\u00edcie afetar\u00e1 a condutividade e a atividade de oxida\u00e7\u00e3o dos produtos de carbono.<\/p>\n<p>\u00c9 imperativo garantir a qualidade da sucata, pois isso ajudar\u00e1 a garantir que o produto final tamb\u00e9m seja de boa qualidade. Os compradores devem se certificar de que os fornecedores de sucata de \u00e2nodo de carbono sejam confi\u00e1veis e ofere\u00e7am pre\u00e7os competitivos. Em seguida, a f\u00e1brica embala a sucata corretamente e a envia no prazo.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclus\u00e3o<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ao seguir essas etapas, as empresas podem garantir que obtenham o m\u00e1ximo de sua sucata e maximizem seu valor. Tem interesse em saber mais sobre sucata de \u00e2nodo de carbono e como maximizar seu valor? Entre em contato conosco hoje mesmo para saber mais!<\/p>","protected":false},"excerpt":{"rendered":"<p>Carbon anode scrap is a valuable but often overlooked by-product of aluminum production. It refers to the residual part after the prebaked anode carbon block is used on the electrolytic cell. By recycling this scrap, companies can help reduce their environmental impact and take advantage of potential benefits. This article discusses the uses, pricing, and [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2717,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[49],"class_list":["post-2714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carbon-material","tag-carbon-anode"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Carbon Anode Scrap Uses and Price | Jinsun Carbon<\/title>\n<meta name=\"description\" content=\"Carbon anode scrap refers to the residual part after the pre-baked anode carbon block is used on the electrolytic cell. It can be recycled.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carbon Anode Scrap Uses and Price\" \/>\n<meta property=\"og:description\" content=\"Carbon anode scrap refers to the residual part after the pre-baked anode carbon block is used on the electrolytic cell. It can be recycled.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/\" \/>\n<meta property=\"og:site_name\" content=\"Jinsun Carbon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-16T09:01:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-01T02:07:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/76f6a5ada3541f85838f1b508aeb8f3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jinsuncarbon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jinsuncarbon_\" \/>\n<meta name=\"twitter:site\" content=\"@jinsuncarbon_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jinsuncarbon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/\"},\"author\":{\"name\":\"jinsuncarbon\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#\\\/schema\\\/person\\\/6d19b66d2a95154652ba3b86492d27b5\"},\"headline\":\"Carbon Anode Scrap Uses and Price\",\"datePublished\":\"2023-02-16T09:01:35+00:00\",\"dateModified\":\"2025-01-01T02:07:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/\"},\"wordCount\":645,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/76f6a5ada3541f85838f1b508aeb8f3.jpg\",\"keywords\":[\"carbon anode\"],\"articleSection\":[\"Carbon material\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/\",\"name\":\"Carbon Anode Scrap Uses and Price | Jinsun Carbon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/76f6a5ada3541f85838f1b508aeb8f3.jpg\",\"datePublished\":\"2023-02-16T09:01:35+00:00\",\"dateModified\":\"2025-01-01T02:07:00+00:00\",\"description\":\"Carbon anode scrap refers to the residual part after the pre-baked anode carbon block is used on the electrolytic cell. It can be recycled.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/76f6a5ada3541f85838f1b508aeb8f3.jpg\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/76f6a5ada3541f85838f1b508aeb8f3.jpg\",\"width\":1024,\"height\":680,\"caption\":\"Carbon anode scrap uses and price\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jinsuncarbon.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carbon Anode Scrap Uses and Price\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"name\":\"Jinsun Carbon\",\"description\":\"We are the successful graphite electrode manufacturer in China\",\"publisher\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jinsuncarbon.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\",\"name\":\"Jinsun Carbon\",\"alternateName\":\"Jinsun Carbon\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Graphite-Electrode-109336238661595\",\"https:\\\/\\\/x.com\\\/jinsuncarbon_\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jinsungraphite\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCysDNyvyR5-3cCWEmpkVC0g\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#\\\/schema\\\/person\\\/6d19b66d2a95154652ba3b86492d27b5\",\"name\":\"jinsuncarbon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"caption\":\"jinsuncarbon\"}},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/carbon-anode-scrap-uses-and-price\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"width\":207,\"height\":80,\"caption\":\"Jinsun Carbon\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Usos e pre\u00e7os da sucata de \u00e2nodo de carbono | Jinsun Carbon","description":"A sucata de \u00e2nodo de carbono refere-se \u00e0 parte residual depois que o bloco de carbono do \u00e2nodo pr\u00e9-cozido \u00e9 usado na c\u00e9lula eletrol\u00edtica. Ela pode ser reciclada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/","og_locale":"pt_BR","og_type":"article","og_title":"Carbon Anode Scrap Uses and Price","og_description":"Carbon anode scrap refers to the residual part after the pre-baked anode carbon block is used on the electrolytic cell. It can be recycled.","og_url":"https:\/\/jinsuncarbon.com\/pt\/uso-e-preco-da-sucata-de-anodo-de-carbono\/","og_site_name":"Jinsun Carbon","article_publisher":"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","article_published_time":"2023-02-16T09:01:35+00:00","article_modified_time":"2025-01-01T02:07:00+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/76f6a5ada3541f85838f1b508aeb8f3.jpg","type":"image\/jpeg"}],"author":"jinsuncarbon","twitter_card":"summary_large_image","twitter_creator":"@jinsuncarbon_","twitter_site":"@jinsuncarbon_","twitter_misc":{"Escrito por":"jinsuncarbon","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#article","isPartOf":{"@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/"},"author":{"name":"jinsuncarbon","@id":"https:\/\/jinsuncarbon.com\/#\/schema\/person\/6d19b66d2a95154652ba3b86492d27b5"},"headline":"Carbon Anode Scrap Uses and Price","datePublished":"2023-02-16T09:01:35+00:00","dateModified":"2025-01-01T02:07:00+00:00","mainEntityOfPage":{"@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/"},"wordCount":645,"commentCount":0,"publisher":{"@id":"https:\/\/jinsuncarbon.com\/#organization"},"image":{"@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#primaryimage"},"thumbnailUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/76f6a5ada3541f85838f1b508aeb8f3.jpg","keywords":["carbon anode"],"articleSection":["Carbon material"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/","url":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/","name":"Usos e pre\u00e7os da sucata de \u00e2nodo de carbono | Jinsun Carbon","isPartOf":{"@id":"https:\/\/jinsuncarbon.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#primaryimage"},"image":{"@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#primaryimage"},"thumbnailUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/76f6a5ada3541f85838f1b508aeb8f3.jpg","datePublished":"2023-02-16T09:01:35+00:00","dateModified":"2025-01-01T02:07:00+00:00","description":"A sucata de \u00e2nodo de carbono refere-se \u00e0 parte residual depois que o bloco de carbono do \u00e2nodo pr\u00e9-cozido \u00e9 usado na c\u00e9lula eletrol\u00edtica. Ela pode ser reciclada.","breadcrumb":{"@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#primaryimage","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/76f6a5ada3541f85838f1b508aeb8f3.jpg","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/76f6a5ada3541f85838f1b508aeb8f3.jpg","width":1024,"height":680,"caption":"Carbon anode scrap uses and price"},{"@type":"BreadcrumbList","@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jinsuncarbon.com\/"},{"@type":"ListItem","position":2,"name":"Carbon Anode Scrap Uses and Price"}]},{"@type":"WebSite","@id":"https:\/\/jinsuncarbon.com\/#website","url":"https:\/\/jinsuncarbon.com\/","name":"Carbono Jinsun","description":"Somos o fabricante bem-sucedido de eletrodos de grafite na China","publisher":{"@id":"https:\/\/jinsuncarbon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jinsuncarbon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Organization","Place"],"@id":"https:\/\/jinsuncarbon.com\/#organization","name":"Carbono Jinsun","alternateName":"Jinsun Carbon","url":"https:\/\/jinsuncarbon.com\/","logo":{"@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#local-main-organization-logo"},"image":{"@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","https:\/\/x.com\/jinsuncarbon_","https:\/\/www.linkedin.com\/in\/jinsungraphite","https:\/\/www.youtube.com\/channel\/UCysDNyvyR5-3cCWEmpkVC0g"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/jinsuncarbon.com\/#\/schema\/person\/6d19b66d2a95154652ba3b86492d27b5","name":"jinsuncarbono","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","caption":"jinsuncarbon"}},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jinsuncarbon.com\/carbon-anode-scrap-uses-and-price\/#local-main-organization-logo","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","width":207,"height":80,"caption":"Jinsun Carbon"}]}},"_links":{"self":[{"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/posts\/2714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/comments?post=2714"}],"version-history":[{"count":10,"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/posts\/2714\/revisions"}],"predecessor-version":[{"id":7188,"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/posts\/2714\/revisions\/7188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/media\/2717"}],"wp:attachment":[{"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/media?parent=2714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/categories?post=2714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/pt\/wp-json\/wp\/v2\/tags?post=2714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}