{"id":2925,"date":"2023-02-25T08:38:11","date_gmt":"2023-02-25T08:38:11","guid":{"rendered":"https:\/\/jinsuncarbon.com\/?p=2925"},"modified":"2025-01-19T01:36:28","modified_gmt":"2025-01-19T01:36:28","slug":"waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt","status":"publish","type":"post","link":"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/","title":{"rendered":"Waar wordt een siliciumcarbide smeltkroes voor gebruikt?"},"content":{"rendered":"<p>Siliciumcarbide smeltkroezen worden gebruikt voor het smelten en raffineren van metalen. Het is duurzamer dan traditionele keramische smeltkroezen en heeft veel voordelen, zoals een hoge temperatuurbestendigheid en thermische geleidbaarheid. In deze blogpost bespreken we de voordelen van het gebruik ervan, hoe je de juiste kiest en wat de voordelen zijn ten opzichte van traditionele materialen.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhoudsopgave<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle tabel met inhoud\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Schakel<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/#What_is_a_silicon_carbide_crucible\" >Wat is een siliciumcarbide smeltkroes?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/#_Uses_of_silicon_carbide_crucible\" >\u00a0Toepassingen van siliciumcarbide smeltkroezen<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/#Metallurgy_and_foundries\" >Metallurgie en gieterijen:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/#Glass_and_ceramics\" >Glas en keramiek:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/#Chemistry_Lab_and_Research\" >Scheikundelab en onderzoek:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/#Jewelry_and_Precious_Metal_Casting\" >Juwelen en edelmetaal gieten:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/#Benefits_of_Using\" >Voordelen van het gebruik van<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/#Conclusion\" >Conclusie<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"What_is_a_silicon_carbide_crucible\"><\/span>Wat is een siliciumcarbide smeltkroes?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Het is voornamelijk gemaakt van <a href=\"https:\/\/jinsuncarbon.com\/nl\/graphite-melting-point\/\">grafietschilfers<\/a> en koolstof gebonden als grondstoffen.  Fabrikanten persen de <a href=\"https:\/\/www.sciencedirect.com\/topics\/materials-science\/hot-isostatic-pressing\" target=\"_blank\" rel=\"noopener\">isostatisch persproces<\/a> volgens een bepaalde verhouding.<\/p>\n<p>De structuur is dicht, waardoor warmteverlies naar de omgeving wordt voorkomen. Het is zeer duurzaam en bestand tegen temperaturen tot 1700 graden Celsius.<\/p>\n<p>Dit maakt het ideaal voor het smelten en raffineren van metalen en legeringen.<\/p>\n<p>Ze staan ook bekend om hun uitstekende thermische geleidbaarheid. Dit betekent dat ze een constante temperatuur kunnen behouden tijdens het smelt- en raffinageproces.<\/p>\n<p>Ze zijn er in vele vormen en maten, en de leveranciers kunnen ze aanpassen aan de behoeften van de gebruiker.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-2928 aligncenter\" src=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/c45c68bf1f4b7b515389d3f23609fcc-scaled.jpg\" alt=\"siliciumcarbide smeltkroes -China leveranciers\" width=\"589\" height=\"196\" srcset=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/c45c68bf1f4b7b515389d3f23609fcc-scaled.jpg 2560w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/c45c68bf1f4b7b515389d3f23609fcc-scaled-600x200.jpg 600w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/c45c68bf1f4b7b515389d3f23609fcc-300x100.jpg 300w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/c45c68bf1f4b7b515389d3f23609fcc-1024x341.jpg 1024w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/c45c68bf1f4b7b515389d3f23609fcc-768x256.jpg 768w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/c45c68bf1f4b7b515389d3f23609fcc-1536x512.jpg 1536w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/c45c68bf1f4b7b515389d3f23609fcc-2048x682.jpg 2048w\" sizes=\"(max-width: 589px) 100vw, 589px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"_Uses_of_silicon_carbide_crucible\"><\/span>\u00a0Toepassingen van siliciumcarbide smeltkroezen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Siliciumcarbide smeltkroezen worden vaak gebruikt bij het smelten van metalen, zoals koper, aluminium, lood, zink, andere non-ferrometalen, staal met een gemiddelde koolstofwaarde, legeringen van zeldzame metalen, enz.<\/p>\n<p>Ze zijn ook bestand tegen slijtage en corrosie en tegen thermische schokken, wat betekent dat je ze kunt gebruiken zonder ze vaak te moeten vervangen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Metallurgy_and_foundries\"><\/span>Metallurgie en gieterijen:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>In de metallurgie en gieterij worden ze veel gebruikt voor het smelten, gieten en raffineren van allerlei metalen, waaronder ferro- en non-ferro legeringen in inductieovens.<\/p>\n<p>Dankzij hun hoge temperatuurbestendigheid en uitstekende thermische geleidbaarheid zijn ze bestand tegen extreem hoge temperaturen en zorgen ze voor een effici\u00ebnte warmteoverdracht, waardoor optimale processen voor het smelten en gieten van metaal mogelijk zijn.<\/p>\n<p>Tegelijkertijd voorkomt de non-reactiviteit van siliciumcarbide vervuiling en garandeert het de zuiverheid en kwaliteit van het gesmolten metaal.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Glass_and_ceramics\"><\/span>Glas en keramiek:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Ze zijn essentieel voor de productie van glaswerk, keramische onderdelen en andere materialen met een hoge temperatuur. Dankzij de uitstekende weerstand tegen thermische schokken zijn ze bestand tegen snelle temperatuurveranderingen zonder te barsten of te barsten.<\/p>\n<p>Ze kunnen worden onderworpen aan extreme verwarmings- en koelcycli. De uitstekende duurzaamheid garandeert betrouwbare prestaties en consistente resultaten, waardoor het de eerste keuze is van ambachtslieden, glasmakers en pottenbakkers.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Chemistry_Lab_and_Research\"><\/span>Scheikundelab en onderzoek:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Deze smeltkroezen verhitten, mengen en reageren chemicali\u00ebn in chemische laboratoria en onderzoeksfaciliteiten dankzij hun uitstekende thermische geleidbaarheid en corrosiebestendigheid tegen zuren, basen en reactieve stoffen. De inerte aard van siliciumcarbide voorkomt vervuiling en zorgt voor nauwkeurige experimenten.<\/p>\n<p>Bovendien maakt hun hoge temperatuurbestendigheid ze essentieel voor wetenschappers en onderzoekers die reacties en materialen bij hoge temperatuur bestuderen, omdat ze bestand zijn tegen zware laboratoriumomstandigheden.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Jewelry_and_Precious_Metal_Casting\"><\/span>Juwelen en edelmetaal gieten:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Goud, zilver, platina en andere edele metalen worden gesmolten en gegoten in smeltkroezen van siliciumcarbide omdat ze bestand zijn tegen de hoge temperaturen die nodig zijn voor metaalbewerking. Ze zorgen voor een gelijkmatige warmteverdeling, wat het smelt- en gietproces precies vergemakkelijkt.<\/p>\n<p>Het heeft ook een uitstekende thermische isolatie, waardoor gesmolten metaal gecontroleerd kan afkoelen en stollen. Dit resulteert in hoogwaardige, goed gevormde sieraden en precieze afgietsels van ingewikkelde ontwerpen, die voldoen aan de behoeften van sieradenmakers en metaalbewerkers.<\/p>\n<p><iframe title=\"BUC-127 Siliciumcarbide Smeltkroes | De Ultieme Smeltoplossing\" width=\"800\" height=\"600\" src=\"https:\/\/www.youtube.com\/embed\/zMxMoSskGfk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Benefits_of_Using\"><\/span>Voordelen van het gebruik van<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li>Het heeft een hoge <a href=\"https:\/\/en.wikipedia.org\/wiki\/Thermal_conductivity\" target=\"_blank\" rel=\"noopener\">thermische geleidbaarheid<\/a> en verkort de tijd om metalen of legeringen te smelten.<\/li>\n<li>Het heeft een sterke weerstand tegen thermische schokken en breekt niet, zelfs niet bij snel afkoelen en verwarmen tijdens het smeltproces.<\/li>\n<li>Het heeft de eigenschappen van grafiet, dus het vervuilt het gesmolten materiaal niet en de hoeveelheid metaalslak die aan de binnenwand blijft kleven is klein.<\/li>\n<li>Door de snelle warmtegeleiding kan het brandstof besparen, uitlaatvervuiling verminderen en het milieu beschermen.<\/li>\n<li>Heeft een sterke weerstand tegen chemische stoffen en corrodeert niet gemakkelijk.<\/li>\n<li>De <a href=\"https:\/\/jinsuncarbon.com\/nl\/product\/grafietkroes\/\">kroes<\/a> heeft een compacte structuur, een lage porositeit en een lange levensduur, tot zes maanden bij regelmatig gebruik.<\/li>\n<\/ul>\n<h2><\/h2>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusie<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Er zijn veel specificaties van siliciumcarbide smeltkroezen, en de prijzen verschillen ook. Pas hem dus aan uw wensen aan. De kroes kan het beste in een droge omgeving worden opgeslagen en werknemers moeten hem voor gebruik voorverwarmen tot 150-200 graden Celsius en dan materialen toevoegen. De prestaties van hen kunnen aan uw productiebehoeften voldoen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Meer bronnen<\/strong>:<\/p>\n<p><a href=\"https:\/\/en.wikipedia.org\/wiki\/Silicon_carbide\" target=\"_blank\" rel=\"noopener\">Siliciumcarbide<\/a>- Bron: Wikipedia<\/p>\n<p><a href=\"https:\/\/www.inductotherm.com\/product_categories\/induction-melting-furnaces\/\" target=\"_blank\" rel=\"noopener\">inductieoven<\/a> - Bron: Inductotherm<\/p>\n<p><a href=\"https:\/\/www.emsdiasum.com\/silicon-single-standard\" target=\"_blank\" rel=\"noopener\">standaard silicium<\/a> - Bron: Microanalyse Element standaarden<\/p>\n<p><a href=\"https:\/\/jinsuncarbon.com\/nl\/product\/grafietkroes\/\" target=\"_blank\" rel=\"noopener\">Grafiet Kroes<\/a> - Bron: JINSUN<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Silicon carbide crucible is used for melting and refining metals. It is more durable than traditional ceramic crucibles and have many advantages, such as high-temperature resistance and thermal conductivity. In this blog post, we will discuss the benefits of using them, how to choose the right one, and their advantages of them over traditional materials. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[20],"class_list":["post-2925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carbon-graphite","tag-graphite-products"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>What is silicon carbide crucible used for? | Jinsun Carbon<\/title>\n<meta name=\"description\" content=\"Silicon carbide crucible is mainly made of flake graphite and silicon carbide as raw materials.\u00a0 Manufacturers press the isostatic pressing process according to a certain proportion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What is silicon carbide crucible used for?\" \/>\n<meta property=\"og:description\" content=\"Silicon carbide crucible is mainly made of flake graphite and silicon carbide as raw materials.\u00a0 Manufacturers press the isostatic pressing process according to a certain proportion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/\" \/>\n<meta property=\"og:site_name\" content=\"Jinsun Carbon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-25T08:38:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-19T01:36:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/84ada2892fb7228b01617dd5521e4d5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jinsuncarbon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jinsuncarbon_\" \/>\n<meta name=\"twitter:site\" content=\"@jinsuncarbon_\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"jinsuncarbon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/\"},\"author\":{\"name\":\"jinsuncarbon\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#\\\/schema\\\/person\\\/6d19b66d2a95154652ba3b86492d27b5\"},\"headline\":\"What is silicon carbide crucible used for?\",\"datePublished\":\"2023-02-25T08:38:11+00:00\",\"dateModified\":\"2025-01-19T01:36:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/\"},\"wordCount\":714,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/84ada2892fb7228b01617dd5521e4d5.jpg\",\"keywords\":[\"Graphite Products\"],\"articleSection\":[\"Carbon Graphite Products\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/\",\"name\":\"What is silicon carbide crucible used for? | Jinsun Carbon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/84ada2892fb7228b01617dd5521e4d5.jpg\",\"datePublished\":\"2023-02-25T08:38:11+00:00\",\"dateModified\":\"2025-01-19T01:36:28+00:00\",\"description\":\"Silicon carbide crucible is mainly made of flake graphite and silicon carbide as raw materials.\u00a0 Manufacturers press the isostatic pressing process according to a certain proportion.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/84ada2892fb7228b01617dd5521e4d5.jpg\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/84ada2892fb7228b01617dd5521e4d5.jpg\",\"width\":1024,\"height\":680,\"caption\":\"silicon carbide crucible uses and price -suppliers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jinsuncarbon.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What is silicon carbide crucible used for?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"name\":\"Jinsun Carbon\",\"description\":\"We are the successful graphite electrode manufacturer in China\",\"publisher\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jinsuncarbon.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\",\"name\":\"Jinsun Carbon\",\"alternateName\":\"Jinsun Carbon\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Graphite-Electrode-109336238661595\",\"https:\\\/\\\/x.com\\\/jinsuncarbon_\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jinsungraphite\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCysDNyvyR5-3cCWEmpkVC0g\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#\\\/schema\\\/person\\\/6d19b66d2a95154652ba3b86492d27b5\",\"name\":\"jinsuncarbon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"caption\":\"jinsuncarbon\"}},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/what-is-silicon-carbide-crucible-used-for\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"width\":207,\"height\":80,\"caption\":\"Jinsun Carbon\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Waar wordt een siliciumcarbide smeltkroes voor gebruikt? | Jinsun Koolstof","description":"Siliciumcarbide smeltkroezen bestaan voornamelijk uit grafietvlokken en siliciumcarbide als grondstoffen.  Fabrikanten persen het isostatisch persproces volgens een bepaalde verhouding.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/","og_locale":"nl_NL","og_type":"article","og_title":"What is silicon carbide crucible used for?","og_description":"Silicon carbide crucible is mainly made of flake graphite and silicon carbide as raw materials.\u00a0 Manufacturers press the isostatic pressing process according to a certain proportion.","og_url":"https:\/\/jinsuncarbon.com\/nl\/waar-wordt-een-smeltkroes-van-siliciumcarbide-voor-gebruikt\/","og_site_name":"Jinsun Carbon","article_publisher":"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","article_published_time":"2023-02-25T08:38:11+00:00","article_modified_time":"2025-01-19T01:36:28+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/84ada2892fb7228b01617dd5521e4d5.jpg","type":"image\/jpeg"}],"author":"jinsuncarbon","twitter_card":"summary_large_image","twitter_creator":"@jinsuncarbon_","twitter_site":"@jinsuncarbon_","twitter_misc":{"Geschreven door":"jinsuncarbon","Geschatte leestijd":"4 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#article","isPartOf":{"@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/"},"author":{"name":"jinsuncarbon","@id":"https:\/\/jinsuncarbon.com\/#\/schema\/person\/6d19b66d2a95154652ba3b86492d27b5"},"headline":"What is silicon carbide crucible used for?","datePublished":"2023-02-25T08:38:11+00:00","dateModified":"2025-01-19T01:36:28+00:00","mainEntityOfPage":{"@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/"},"wordCount":714,"commentCount":0,"publisher":{"@id":"https:\/\/jinsuncarbon.com\/#organization"},"image":{"@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#primaryimage"},"thumbnailUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/84ada2892fb7228b01617dd5521e4d5.jpg","keywords":["Graphite Products"],"articleSection":["Carbon Graphite Products"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/","url":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/","name":"Waar wordt een siliciumcarbide smeltkroes voor gebruikt? | Jinsun Koolstof","isPartOf":{"@id":"https:\/\/jinsuncarbon.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#primaryimage"},"image":{"@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#primaryimage"},"thumbnailUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/84ada2892fb7228b01617dd5521e4d5.jpg","datePublished":"2023-02-25T08:38:11+00:00","dateModified":"2025-01-19T01:36:28+00:00","description":"Siliciumcarbide smeltkroezen bestaan voornamelijk uit grafietvlokken en siliciumcarbide als grondstoffen.  Fabrikanten persen het isostatisch persproces volgens een bepaalde verhouding.","breadcrumb":{"@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#primaryimage","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/84ada2892fb7228b01617dd5521e4d5.jpg","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2023\/02\/84ada2892fb7228b01617dd5521e4d5.jpg","width":1024,"height":680,"caption":"silicon carbide crucible uses and price -suppliers"},{"@type":"BreadcrumbList","@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jinsuncarbon.com\/"},{"@type":"ListItem","position":2,"name":"What is silicon carbide crucible used for?"}]},{"@type":"WebSite","@id":"https:\/\/jinsuncarbon.com\/#website","url":"https:\/\/jinsuncarbon.com\/","name":"Jinsun Koolstof","description":"Wij zijn de succesvolle grafietelektrodefabrikant in China","publisher":{"@id":"https:\/\/jinsuncarbon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jinsuncarbon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":["Organization","Place"],"@id":"https:\/\/jinsuncarbon.com\/#organization","name":"Jinsun Koolstof","alternateName":"Jinsun Carbon","url":"https:\/\/jinsuncarbon.com\/","logo":{"@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#local-main-organization-logo"},"image":{"@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","https:\/\/x.com\/jinsuncarbon_","https:\/\/www.linkedin.com\/in\/jinsungraphite","https:\/\/www.youtube.com\/channel\/UCysDNyvyR5-3cCWEmpkVC0g"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/jinsuncarbon.com\/#\/schema\/person\/6d19b66d2a95154652ba3b86492d27b5","name":"jinsuncarbon","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","caption":"jinsuncarbon"}},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/jinsuncarbon.com\/what-is-silicon-carbide-crucible-used-for\/#local-main-organization-logo","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","width":207,"height":80,"caption":"Jinsun Carbon"}]}},"_links":{"self":[{"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/posts\/2925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/comments?post=2925"}],"version-history":[{"count":27,"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/posts\/2925\/revisions"}],"predecessor-version":[{"id":4558,"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/posts\/2925\/revisions\/4558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/media\/2932"}],"wp:attachment":[{"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/media?parent=2925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/categories?post=2925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/nl\/wp-json\/wp\/v2\/tags?post=2925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}