{"id":6838,"date":"2024-11-29T01:31:38","date_gmt":"2024-11-29T01:31:38","guid":{"rendered":"https:\/\/jinsuncarbon.com\/?post_type=product&#038;p=6838"},"modified":"2024-12-01T12:53:29","modified_gmt":"2024-12-01T12:53:29","slug":"bande-de-graphite","status":"publish","type":"product","link":"https:\/\/jinsuncarbon.com\/fr\/produit-2\/bande-de-graphite\/","title":{"rendered":"Bande de graphite"},"content":{"rendered":"<h2>Propri\u00e9t\u00e9s des bandes de graphite<\/h2>\n<p>La bande de graphite a une conductivit\u00e9 thermique, ce qui signifie que la conduction de la bande de graphite est une excellente condition de dissipation de la chaleur dans un environnement. C'est \u00e9galement un conducteur d'\u00e9lectricit\u00e9 fiable, utilis\u00e9 dans des applications telles que les batteries \u00e9lectriques, les moteurs \u00e9lectriques d'orgueil, les syst\u00e8mes \u00e9lectriques. Une autre propri\u00e9t\u00e9 physique importante, est la qualification de lubrifiant, de sorte qu'il peut r\u00e9duire la friction entre les surfaces et \u00eatre capable de supporter des charges importantes tout en r\u00e9duisant simultan\u00e9ment l'usure des composants. Il est \u00e9galement r\u00e9sistant \u00e0 la corrosion, ce qui lui permet de travailler dans des environnements difficiles sans craindre d'\u00eatre endommag\u00e9. Il est \u00e9galement flexible et facile, le plus important \u00e9tant de pr\u00e9senter des bandes de graphite faciles \u00e0 fa\u00e7onner et \u00e0 d\u00e9couper.<\/p>\n<h2>Utilisations de la bande de graphite<\/h2>\n<h3>Applications d'\u00e9tanch\u00e9it\u00e9<\/h3>\n<p>Pour l'\u00e9tanch\u00e9it\u00e9, la bande de graphite affecte efficacement les performances. Elle est utilis\u00e9e pour les joints des pompes, des vannes, des compresseurs et d'autres \u00e9l\u00e9ments qui cr\u00e9ent une \u00e9tanch\u00e9it\u00e9 dans des conditions extr\u00eames. Sa capacit\u00e9 \u00e0 r\u00e9sister aux temp\u00e9ratures et aux pressions \u00e9lev\u00e9es, ainsi qu'\u00e0 l'exposition aux produits chimiques, en fait une solution de choix pour les applications d'\u00e9tanch\u00e9it\u00e9 dans les environnements difficiles. Les bandes de graphite peuvent \u00e9galement \u00eatre utilis\u00e9es dans la fabrication de joints, offrant ainsi des solutions d'\u00e9tanch\u00e9it\u00e9 dans une vari\u00e9t\u00e9 d'industries - automobile, a\u00e9rospatiale et secteur p\u00e9trochimique.<\/p>\n<h3>Gestion de la chaleur<\/h3>\n<p>Le ruban adh\u00e9sif est un excellent conducteur de chaleur. Il a \u00e9galement une bonne conductivit\u00e9 thermique et une capacit\u00e9 \u00e0 disperser la chaleur, ce qui permet d'\u00e9viter la surchauffe de diff\u00e9rents syst\u00e8mes. Il est utilis\u00e9 dans <a href=\"https:\/\/jinsuncarbon.com\/fr\/quest-ce-quun-echangeur-de-chaleur-en-graphite\/\">\u00e9changeurs de chaleur<\/a>Les bandes de graphite sont utilis\u00e9es dans les radiateurs ainsi que dans d'autres syst\u00e8mes de refroidissement pour assurer un contr\u00f4le efficace de la temp\u00e9rature. Ou, pour utiliser un terme plus technique, la bande de graphite trouve son application dans les appareils \u00e9lectroniques en tant que dissipateur de chaleur ou mat\u00e9riau d'interface thermique. Elle permet de maintenir les composants sensibles \u00e0 des temp\u00e9ratures stables. Cette propri\u00e9t\u00e9 de conduire et de disperser la chaleur en fait un mat\u00e9riau essentiel pour la production d'appareils \u00e9lectroniques, des smartphones aux ordinateurs portables en passant par les \u00e9clairages LED.<\/p>\n<h3>Applications \u00e9lectriques<\/h3>\n<p>En raison de sa bonne conductivit\u00e9 \u00e9lectrique, la bande de graphite est utilis\u00e9e dans un large \u00e9ventail de syst\u00e8mes et de composants. Elle est souvent utilis\u00e9e dans les batteries, les moteurs \u00e9lectriques, les piles \u00e0 combustible et d'autres dispositifs \u00e9lectriques. Dans les batteries, la bande de graphite sert d'\u00e9lectrode pour les cycles de charge\/d\u00e9charge. En raison de sa conductivit\u00e9, le graphite est utilis\u00e9 pour les contacts \u00e9lectriques, les balais et les syst\u00e8mes de mise \u00e0 la terre, l\u00e0 o\u00f9 un flux fiable de courant \u00e9lectrique doit \u00eatre maintenu.<\/p>\n<h3>D\u00e9moulage<\/h3>\n<p>De plus, la bande de graphite est un bon agent de d\u00e9moulage pour emp\u00eacher tout ce qui sera utilis\u00e9 de coller aux moules. Si vous devez l'utiliser pour d'autres choses, comme le m\u00e9tal, la bande de graphite est un bon agent de d\u00e9moulage. <a href=\"https:\/\/en.wikipedia.org\/wiki\/Casting\" target=\"_blank\" rel=\"noopener\">coul\u00e9e<\/a>Les fabricants de moules, de moules en plastique, de moules en caoutchouc et d'autres proc\u00e9d\u00e9s se souviennent qu'ils en ont besoin pour lib\u00e9rer les mat\u00e9riaux en douceur. Quelle que soit leur forme, les produits moul\u00e9s conservent leur forme et leurs caract\u00e9ristiques de surface sans d\u00e9faut gr\u00e2ce \u00e0 leur caract\u00e8re antiadh\u00e9sif. La bande de graphite est particuli\u00e8rement adapt\u00e9e au moulage \u00e0 haute temp\u00e9rature ; elle se comporte tr\u00e8s bien, m\u00eame \u00e0 haute temp\u00e9rature. Cela permet de r\u00e9duire les d\u00e9lais de production et de maximiser l'efficacit\u00e9 globale de la fabrication.<\/p>\n<h3>Lubrification<\/h3>\n<p>La bande de graphite est un excellent lubrifiant et permet de r\u00e9duire les frottements entre les pi\u00e8ces mobiles. Elle peut \u00eatre utilis\u00e9e dans des applications o\u00f9 les lubrifiants normaux sont utiles, par exemple dans des conditions de vide pouss\u00e9 ou de temp\u00e9rature \u00e9lev\u00e9e. Elle lubrifie efficacement sans n\u00e9cessiter d'huiles ou de graisses suppl\u00e9mentaires, m\u00eame dans des conditions de froid, de chaleur et de charge extr\u00eames. Les bandes de graphite ont d'innombrables utilisations dans les machines, les lignes de convoyage, les pi\u00e8ces automobiles et les machines envoy\u00e9es dans l'espace. Bien plus r\u00e9sistante que les lubrifiants ordinaires qui s'\u00e9vaporent et se d\u00e9composent rapidement, la bande de graphite peut \u00eatre utilis\u00e9e dans les domaines o\u00f9 l'on recherche les produits et la protection les meilleurs et les plus durables.<\/p>\n<h3>Applications industrielles<\/h3>\n<p>Mat\u00e9riau industriel extr\u00eamement polyvalent, la bande de graphite r\u00e9siste \u00e0 la chaleur, \u00e0 la corrosion et aux produits chimiques. On le trouve dans les usines chimiques, les raffineries, les centrales \u00e9lectriques et les usines de traitement des m\u00e9taux. En raison de sa stabilit\u00e9 thermique, il est id\u00e9al pour une utilisation en tant qu'isolant. <a href=\"https:\/\/jinsuncarbon.com\/fr\/produit-2\/revetement-de-four-en-graphite\/\">doublure<\/a> mat\u00e9riau \u00e0 haute temp\u00e9rature <a href=\"https:\/\/en.wikipedia.org\/wiki\/Furnace_(central_heating)\" target=\"_blank\" rel=\"noopener\">fours<\/a> et les fours. Dans l'industrie chimique, o\u00f9 les bandes de graphite sont soumises \u00e0 des processus chimiques agressifs, elles sont pr\u00e9sentes dans les composants des \u00e9changeurs de chaleur, dans les pompes et les vannes pour les produits chimiques agressifs. La r\u00e9sistance \u00e0 la corrosion du mat\u00e9riau leur conf\u00e8re une longue dur\u00e9e de vie et un minimum de r\u00e9parations ou de remplacements.<\/p>\n<h2>Avantages des bandes de graphite<\/h2>\n<p>L'avantage de la bande de graphite est qu'elle est r\u00e9sistante aux temp\u00e9ratures \u00e9lev\u00e9es et peut donc \u00eatre utilis\u00e9e dans des environnements o\u00f9 il y a de la chaleur.<br \/>\nEn outre, c'est un bon conducteur d'\u00e9lectricit\u00e9, ce qui permet de l'utiliser pour des applications \u00e9lectroniques. Les bandes de graphite ont d'excellentes propri\u00e9t\u00e9s lubrifiantes qui minimisent les frottements et contribuent \u00e0 la long\u00e9vit\u00e9 des composants. Elles sont \u00e9galement r\u00e9sistantes \u00e0 la corrosion, ce qui permet de les utiliser dans des conditions environnementales difficiles o\u00f9 des produits chimiques ou de l'humidit\u00e9 sont en contact avec l'environnement. Elles sont flexibles et peuvent \u00eatre coup\u00e9es \u00e0 la taille voulue, ce qui permet de les utiliser dans une grande vari\u00e9t\u00e9 d'applications. En outre, les bandes de graphite sont tr\u00e8s durables et ne se d\u00e9gradent pas dans des situations de haute performance. Il s'agit d'un produit durable, abordable et ne n\u00e9cessitant que peu ou pas d'entretien.<\/p>","protected":false},"excerpt":{"rendered":"<p>Une bande de graphite est une fine bande horizontale de graphite. On la trouve principalement dans les industries o\u00f9 il y a un risque de chaleur, de friction ou de probl\u00e8mes d'\u00e9tanch\u00e9it\u00e9. Elle est flexible et durable. Elle est disponible en diff\u00e9rentes formes et tailles pour r\u00e9pondre \u00e0 diff\u00e9rents besoins.<\/p>\n<p>La bande de graphite est l'une des formes de graphite les plus r\u00e9put\u00e9es. Elle pr\u00e9sente une r\u00e9sistance \u00e9lev\u00e9e \u00e0 la chaleur. Elle poss\u00e8de \u00e9galement une bonne conductivit\u00e9 \u00e9lectrique et un pouvoir lubrifiant tr\u00e8s \u00e9lev\u00e9. Gr\u00e2ce \u00e0 ces caract\u00e9ristiques, il est le plus utilis\u00e9 dans de nombreuses applications.<\/p>","protected":false},"featured_media":6846,"template":"","meta":[],"product_brand":[],"product_cat":[38],"product_tag":[],"class_list":["post-6838","product","type-product","status-publish","has-post-thumbnail","product_cat-graphite-products","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Graphite Strip Manufacturer | Jinsun Carbon<\/title>\n<meta name=\"description\" content=\"Graphite strip is one of the most reputed forms of graphite. It has a high resistance to heat. It also has good electrical conductivity and very high lubrication\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jinsuncarbon.com\/fr\/produit-2\/bande-de-graphite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graphite Strip\" \/>\n<meta property=\"og:description\" content=\"Graphite strip is one of the most reputed forms of graphite. It has a high resistance to heat. It also has good electrical conductivity and very high lubrication\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jinsuncarbon.com\/fr\/produit-2\/bande-de-graphite\/\" \/>\n<meta property=\"og:site_name\" content=\"Jinsun Carbon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-01T12:53:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/11\/Graphite-stirp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@jinsuncarbon_\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/\",\"name\":\"Graphite Strip Manufacturer | Jinsun Carbon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Graphite-stirp.jpg\",\"datePublished\":\"2024-11-29T01:31:38+00:00\",\"dateModified\":\"2024-12-01T12:53:29+00:00\",\"description\":\"Graphite strip is one of the most reputed forms of graphite. It has a high resistance to heat. It also has good electrical conductivity and very high lubrication\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Graphite-stirp.jpg\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Graphite-stirp.jpg\",\"width\":1024,\"height\":763,\"caption\":\"Graphite strip\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jinsuncarbon.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/jinsuncarbon.com\\\/graphite-carbon\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Graphite Strip\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"name\":\"Jinsun Carbon\",\"description\":\"We are the successful graphite electrode manufacturer in China\",\"publisher\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jinsuncarbon.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\",\"name\":\"Jinsun Carbon\",\"alternateName\":\"Jinsun Carbon\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Graphite-Electrode-109336238661595\",\"https:\\\/\\\/x.com\\\/jinsuncarbon_\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jinsungraphite\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCysDNyvyR5-3cCWEmpkVC0g\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/graphite-strip\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"width\":207,\"height\":80,\"caption\":\"Jinsun Carbon\"}]}<\/script>\n<meta property=\"product:price:currency\" content=\"USD\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fabricant de bandes de graphite | Jinsun Carbon","description":"La bande de graphite est l'une des formes de graphite les plus r\u00e9put\u00e9es. Elle pr\u00e9sente une r\u00e9sistance \u00e9lev\u00e9e \u00e0 la chaleur. Il poss\u00e8de \u00e9galement une bonne conductivit\u00e9 \u00e9lectrique et un pouvoir lubrifiant tr\u00e8s \u00e9lev\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jinsuncarbon.com\/fr\/produit-2\/bande-de-graphite\/","og_locale":"fr_FR","og_type":"article","og_title":"Graphite Strip","og_description":"Graphite strip is one of the most reputed forms of graphite. It has a high resistance to heat. It also has good electrical conductivity and very high lubrication","og_url":"https:\/\/jinsuncarbon.com\/fr\/produit-2\/bande-de-graphite\/","og_site_name":"Jinsun Carbon","article_publisher":"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","article_modified_time":"2024-12-01T12:53:29+00:00","og_image":[{"width":1024,"height":763,"url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/11\/Graphite-stirp.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@jinsuncarbon_","twitter_misc":{"Prix":"","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/","url":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/","name":"Fabricant de bandes de graphite | Jinsun Carbon","isPartOf":{"@id":"https:\/\/jinsuncarbon.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/#primaryimage"},"image":{"@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/#primaryimage"},"thumbnailUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/11\/Graphite-stirp.jpg","datePublished":"2024-11-29T01:31:38+00:00","dateModified":"2024-12-01T12:53:29+00:00","description":"La bande de graphite est l'une des formes de graphite les plus r\u00e9put\u00e9es. Elle pr\u00e9sente une r\u00e9sistance \u00e9lev\u00e9e \u00e0 la chaleur. Il poss\u00e8de \u00e9galement une bonne conductivit\u00e9 \u00e9lectrique et un pouvoir lubrifiant tr\u00e8s \u00e9lev\u00e9.","breadcrumb":{"@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jinsuncarbon.com\/product\/graphite-strip\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/#primaryimage","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/11\/Graphite-stirp.jpg","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/11\/Graphite-stirp.jpg","width":1024,"height":763,"caption":"Graphite strip"},{"@type":"BreadcrumbList","@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jinsuncarbon.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/jinsuncarbon.com\/graphite-carbon\/"},{"@type":"ListItem","position":3,"name":"Graphite Strip"}]},{"@type":"WebSite","@id":"https:\/\/jinsuncarbon.com\/#website","url":"https:\/\/jinsuncarbon.com\/","name":"Jinsun Carbon","description":"Nous sommes le fabricant d'\u00e9lectrodes en graphite le plus performant de Chine.","publisher":{"@id":"https:\/\/jinsuncarbon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jinsuncarbon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Organization","Place"],"@id":"https:\/\/jinsuncarbon.com\/#organization","name":"Jinsun Carbon","alternateName":"Jinsun Carbon","url":"https:\/\/jinsuncarbon.com\/","logo":{"@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/#local-main-organization-logo"},"image":{"@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","https:\/\/x.com\/jinsuncarbon_","https:\/\/www.linkedin.com\/in\/jinsungraphite","https:\/\/www.youtube.com\/channel\/UCysDNyvyR5-3cCWEmpkVC0g"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/jinsuncarbon.com\/product\/graphite-strip\/#local-main-organization-logo","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","width":207,"height":80,"caption":"Jinsun Carbon"}]},"product_price_currency":"USD","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/jinsuncarbon.com\/fr\/wp-json\/wp\/v2\/product\/6838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jinsuncarbon.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jinsuncarbon.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/fr\/wp-json\/wp\/v2\/media\/6846"}],"wp:attachment":[{"href":"https:\/\/jinsuncarbon.com\/fr\/wp-json\/wp\/v2\/media?parent=6838"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/fr\/wp-json\/wp\/v2\/product_brand?post=6838"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/fr\/wp-json\/wp\/v2\/product_cat?post=6838"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/fr\/wp-json\/wp\/v2\/product_tag?post=6838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}