{"id":7103,"date":"2024-12-21T15:21:24","date_gmt":"2024-12-21T15:21:24","guid":{"rendered":"https:\/\/jinsuncarbon.com\/?post_type=product&#038;p=7103"},"modified":"2024-12-21T23:29:04","modified_gmt":"2024-12-21T23:29:04","slug":"pasta-de-apisonar","status":"publish","type":"product","link":"https:\/\/jinsuncarbon.com\/es_ar\/producto\/pasta-de-apisonar\/","title":{"rendered":"Pasta de apisonar"},"content":{"rendered":"<p class=\"ql-align-justify\">La pasta de embestir incluye principalmente las siguientes categor\u00edas.<\/p>\n<h3 class=\"ql-align-justify\">Pasta de apisonar en fr\u00edo<\/h3>\n<p class=\"ql-align-justify\">Se puede apisonar a temperatura ambiente, comodidad de construcci\u00f3n, sin equipo de calefacci\u00f3n adicional. Puede reducir eficazmente los costes de construcci\u00f3n y el consumo de energ\u00eda. Tiene cierta plasticidad antes del tostado, puede rellenar mejor el hueco entre el bloque de carb\u00f3n cat\u00f3dico. Y formar una uni\u00f3n firme con el <a href=\"https:\/\/jinsuncarbon.com\/es_ar\/producto\/bloques-de-carbono\/\">bloque de carb\u00f3n<\/a> en el proceso de tostado posterior. Para garantizar la integridad de la estructura del c\u00e1todo y la conductividad el\u00e9ctrica. Es adecuado para plantas de aluminio electrol\u00edtico con requisitos especiales en cuanto a condiciones de construcci\u00f3n o suministro limitado de energ\u00eda. Especialmente la construcci\u00f3n y el mantenimiento de peque\u00f1as celdas electrol\u00edticas.<\/p>\n<h3 class=\"ql-align-justify\">Pasta de estampaci\u00f3n en caliente<\/h3>\n<p class=\"ql-align-justify\">Es necesario llevar a cabo la construcci\u00f3n de bateo a una temperatura m\u00e1s alta, normalmente calentada a unos 100\u00b0C. En estas condiciones, aumenta su fluidez y adherencia. Y puede rellenar mejor los huecos y poros del bloque de carbono cat\u00f3dico, formando una estructura cat\u00f3dica m\u00e1s densa. De este modo, se mejora la conductividad y la resistencia a la erosi\u00f3n. Es adecuado para la construcci\u00f3n de celdas electrol\u00edticas de aluminio modernas, eficientes y a gran escala. Es \u00fatil para mejorar el rendimiento general y la eficiencia de producci\u00f3n de la c\u00e9lula electrol\u00edtica. Sin embargo, el entorno de construcci\u00f3n y los equipos de calefacci\u00f3n son muy exigentes, y el coste de construcci\u00f3n es relativamente elevado.<\/p>\n<h2 class=\"ql-align-justify\">Ventajas<\/h2>\n<p class=\"ql-align-justify\"><strong>Buena conductividad el\u00e9ctrica<\/strong><\/p>\n<p class=\"ql-align-justify\">Puede conducir eficazmente la corriente para garantizar una reacci\u00f3n electroqu\u00edmica fluida en la c\u00e9lula electrol\u00edtica.<\/p>\n<p class=\"ql-align-justify\"><strong>Resistencia a altas temperaturas<\/strong><\/p>\n<p class=\"ql-align-justify\">Puede funcionar de forma estable en el entorno de alta temperatura de la electr\u00f3lisis del aluminio (unos 950-970 \u00b0C) durante mucho tiempo. Esto mantiene la integridad de la estructura del c\u00e1todo.<\/p>\n<p class=\"ql-align-justify\"><strong>Buena adherencia con el bloque de carb\u00f3n cat\u00f3dico<\/strong><\/p>\n<p class=\"ql-align-justify\">Puede combinarse estrechamente para evitar la penetraci\u00f3n de electrolitos, prolongando as\u00ed la vida \u00fatil del c\u00e1todo.<\/p>\n<p class=\"ql-align-justify\">Adem\u00e1s, podemos personalizar la pasta de apisonamiento de acuerdo con los diferentes dise\u00f1os de celdas electrol\u00edticas y los requisitos del proceso durante el proceso de producci\u00f3n. Para satisfacer diversas necesidades de producci\u00f3n y garantizar la estabilidad y la eficiencia de la producci\u00f3n electrol\u00edtica de aluminio.<\/p>\n<h2 class=\"ql-align-justify\">Usos de la pasta de apisonar<\/h2>\n<p class=\"ql-align-justify\">La pasta de apisonamiento se utiliza ampliamente en la industria de la electr\u00f3lisis del aluminio.<\/p>\n<p class=\"ql-align-justify\">En el proceso de ensamblaje de la c\u00e9lula electrol\u00edtica de aluminio, la pasta de apisonado en fr\u00edo o la pasta de apisonado en caliente se rellenar\u00e1 con precisi\u00f3n en el hueco del <a href=\"https:\/\/jinsuncarbon.com\/es_ar\/producto\/bloque-catodico\/\">bloque de carb\u00f3n cat\u00f3dico<\/a> seg\u00fan la situaci\u00f3n real. Y tras el tostado y el curado, se construir\u00e1 una base cat\u00f3dica conductora completa con un rendimiento excelente para construir una v\u00eda de transporte de electrones para la reacci\u00f3n de reducci\u00f3n de los iones de aluminio. Y asegura la reacci\u00f3n electrol\u00edtica estable y eficiente.<\/p>\n<p class=\"ql-align-justify\">Al mismo tiempo, puede utilizar la pasta de apisonamiento en el lado para proteger eficazmente la estructura lateral de la <a href=\"https:\/\/en.wikipedia.org\/wiki\/Electrolytic_cell\" target=\"_blank\" rel=\"noopener\">c\u00e9lula electrol\u00edtica<\/a>. Y resistir la erosi\u00f3n de electrolito de alta temperatura y <a href=\"https:\/\/en.wikipedia.org\/wiki\/Aluminium#:~:text=Aluminium%20(or%20aluminum%20in%20North,surface%20when%20exposed%20to%20air.\" target=\"_blank\" rel=\"noopener\">aluminio<\/a> l\u00edquido. Mantener el equilibrio t\u00e9rmico de la c\u00e9lula electrol\u00edtica y el estado estable del revestimiento, reducir la p\u00e9rdida de calor. Y mejorar los beneficios econ\u00f3micos y la seguridad de la producci\u00f3n electrol\u00edtica.<\/p>\n<p class=\"ql-align-justify\">Adem\u00e1s, los diferentes tipos de pasta de apisonamiento con sus propias caracter\u00edsticas, no s\u00f3lo se utiliza en la construcci\u00f3n inicial de nuevas c\u00e9lulas electrol\u00edticas, pero tambi\u00e9n se utiliza en el mantenimiento y renovaci\u00f3n de las c\u00e9lulas electrol\u00edticas de edad. Para el desarrollo sostenible y constante de la industria del aluminio para sentar una base s\u00f3lida. Es el material b\u00e1sico fundamental en la producci\u00f3n de electr\u00f3lisis de aluminio.<\/p>","protected":false},"excerpt":{"rendered":"<p>La pasta de apisonamiento es un tipo de pasta de carbono, tambi\u00e9n conocida como pasta de apisonamiento, hay dos tipos: pasta de apisonamiento en fr\u00edo y pasta de apisonamiento en caliente. Se utiliza principalmente para colocar bloques de carb\u00f3n cat\u00f3dico, rellenar huecos cat\u00f3dicos, unir barras de acero cat\u00f3dico, etc. en celdas electrol\u00edticas de aluminio. La pasta de apisonado est\u00e1 hecha de antracita, coque, grafito, asfalto y otras materias primas en una proporci\u00f3n espec\u00edfica. Tiene una excelente conductividad el\u00e9ctrica y t\u00e9rmica, bajo contenido de cenizas, resistencia al l\u00edquido de aluminio y a la corrosi\u00f3n electrol\u00edtica, y un buen rendimiento de sinterizaci\u00f3n. Por lo tanto, puede mejorar el rendimiento de las celdas electrol\u00edticas de aluminio y prolongar su vida \u00fatil. Y garantizar la reacci\u00f3n electrol\u00edtica continua y eficiente.<\/p>\n<p class=\"ql-align-justify\">","protected":false},"featured_media":7104,"template":"","meta":[],"product_brand":[],"product_cat":[39],"product_tag":[],"class_list":["post-7103","product","type-product","status-publish","has-post-thumbnail","product_cat-carbon-products","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ramming Paste | Jinsun Carbon<\/title>\n<meta name=\"description\" content=\"Ramming paste is a kind of carbon paste, also known as tamping paste, which is mainly used for laying cathode carbon blocks, filling cathode gaps, bonding cathode steel bars, etc. in aluminum electrolytic cells.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jinsuncarbon.com\/es_ar\/producto\/pasta-de-apisonar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ramming Paste\" \/>\n<meta property=\"og:description\" content=\"Ramming paste is a kind of carbon paste, also known as tamping paste, which is mainly used for laying cathode carbon blocks, filling cathode gaps, bonding cathode steel bars, etc. in aluminum electrolytic cells.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jinsuncarbon.com\/es_ar\/producto\/pasta-de-apisonar\/\" \/>\n<meta property=\"og:site_name\" content=\"Jinsun Carbon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-21T23:29:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/12\/Ramming-Paste-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@jinsuncarbon_\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/\",\"name\":\"Ramming Paste | Jinsun Carbon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Ramming-Paste-.jpg\",\"datePublished\":\"2024-12-21T15:21:24+00:00\",\"dateModified\":\"2024-12-21T23:29:04+00:00\",\"description\":\"Ramming paste is a kind of carbon paste, also known as tamping paste, which is mainly used for laying cathode carbon blocks, filling cathode gaps, bonding cathode steel bars, etc. in aluminum electrolytic cells.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Ramming-Paste-.jpg\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Ramming-Paste-.jpg\",\"width\":1024,\"height\":763,\"caption\":\"Ramming Paste\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jinsuncarbon.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/jinsuncarbon.com\\\/graphite-carbon\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ramming Paste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"name\":\"Jinsun Carbon\",\"description\":\"We are the successful graphite electrode manufacturer in China\",\"publisher\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jinsuncarbon.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\",\"name\":\"Jinsun Carbon\",\"alternateName\":\"Jinsun Carbon\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Graphite-Electrode-109336238661595\",\"https:\\\/\\\/x.com\\\/jinsuncarbon_\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jinsungraphite\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCysDNyvyR5-3cCWEmpkVC0g\"],\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/product\\\/ramming-paste\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"width\":207,\"height\":80,\"caption\":\"Jinsun Carbon\"}]}<\/script>\n<meta property=\"product:price:currency\" content=\"USD\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pasta de apisonar | Jinsun Carbon","description":"La pasta de apisonamiento es un tipo de pasta de carbono, tambi\u00e9n conocida como pasta de apisonamiento, que se utiliza principalmente para colocar bloques de carbono de c\u00e1todo, rellenar huecos de c\u00e1todo, unir barras de acero de c\u00e1todo, etc. en celdas electrol\u00edticas de aluminio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jinsuncarbon.com\/es_ar\/producto\/pasta-de-apisonar\/","og_locale":"es_ES","og_type":"article","og_title":"Ramming Paste","og_description":"Ramming paste is a kind of carbon paste, also known as tamping paste, which is mainly used for laying cathode carbon blocks, filling cathode gaps, bonding cathode steel bars, etc. in aluminum electrolytic cells.","og_url":"https:\/\/jinsuncarbon.com\/es_ar\/producto\/pasta-de-apisonar\/","og_site_name":"Jinsun Carbon","article_publisher":"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","article_modified_time":"2024-12-21T23:29:04+00:00","og_image":[{"width":1024,"height":763,"url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/12\/Ramming-Paste-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@jinsuncarbon_","twitter_misc":{"Price":"","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/","url":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/","name":"Pasta de apisonar | Jinsun Carbon","isPartOf":{"@id":"https:\/\/jinsuncarbon.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/#primaryimage"},"image":{"@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/#primaryimage"},"thumbnailUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/12\/Ramming-Paste-.jpg","datePublished":"2024-12-21T15:21:24+00:00","dateModified":"2024-12-21T23:29:04+00:00","description":"La pasta de apisonamiento es un tipo de pasta de carbono, tambi\u00e9n conocida como pasta de apisonamiento, que se utiliza principalmente para colocar bloques de carbono de c\u00e1todo, rellenar huecos de c\u00e1todo, unir barras de acero de c\u00e1todo, etc. en celdas electrol\u00edticas de aluminio.","breadcrumb":{"@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jinsuncarbon.com\/product\/ramming-paste\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/#primaryimage","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/12\/Ramming-Paste-.jpg","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2024\/12\/Ramming-Paste-.jpg","width":1024,"height":763,"caption":"Ramming Paste"},{"@type":"BreadcrumbList","@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jinsuncarbon.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/jinsuncarbon.com\/graphite-carbon\/"},{"@type":"ListItem","position":3,"name":"Ramming Paste"}]},{"@type":"WebSite","@id":"https:\/\/jinsuncarbon.com\/#website","url":"https:\/\/jinsuncarbon.com\/","name":"Jinsun Carbon","description":"Somos el fabricante de electrodos de grafito con m\u00e1s \u00e9xito de China","publisher":{"@id":"https:\/\/jinsuncarbon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jinsuncarbon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":["Organization","Place"],"@id":"https:\/\/jinsuncarbon.com\/#organization","name":"Jinsun Carbon","alternateName":"Jinsun Carbon","url":"https:\/\/jinsuncarbon.com\/","logo":{"@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/#local-main-organization-logo"},"image":{"@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","https:\/\/x.com\/jinsuncarbon_","https:\/\/www.linkedin.com\/in\/jinsungraphite","https:\/\/www.youtube.com\/channel\/UCysDNyvyR5-3cCWEmpkVC0g"],"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/jinsuncarbon.com\/product\/ramming-paste\/#local-main-organization-logo","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","width":207,"height":80,"caption":"Jinsun Carbon"}]},"product_price_currency":"USD","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/jinsuncarbon.com\/es_ar\/wp-json\/wp\/v2\/product\/7103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jinsuncarbon.com\/es_ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/jinsuncarbon.com\/es_ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/es_ar\/wp-json\/wp\/v2\/media\/7104"}],"wp:attachment":[{"href":"https:\/\/jinsuncarbon.com\/es_ar\/wp-json\/wp\/v2\/media?parent=7103"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/es_ar\/wp-json\/wp\/v2\/product_brand?post=7103"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/es_ar\/wp-json\/wp\/v2\/product_cat?post=7103"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/es_ar\/wp-json\/wp\/v2\/product_tag?post=7103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}