{"id":7642,"date":"2025-02-17T01:29:24","date_gmt":"2025-02-17T01:29:24","guid":{"rendered":"https:\/\/jinsuncarbon.com\/?p=7642"},"modified":"2025-02-17T01:44:34","modified_gmt":"2025-02-17T01:44:34","slug":"dichte-von-kohlenstoff","status":"publish","type":"post","link":"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/","title":{"rendered":"Die Dichte von Kohlenstoff - ein kurzer \u00dcberblick"},"content":{"rendered":"<p>Kohlenstoff ist einer der Grundbausteine unseres Universums, und jede Wissenschaft, die sich mit ihm befasst, ist in der organischen Welt, bei industriellen Anwendungen und in der Werkstoffkunde sehr modern. Die Dichte, also die Masse der Kohlenstoffatome pro Volumeneinheit, ist eine der wichtigsten Eigenschaften von Kohlenstoff. Die Dichte von Kohlenstoff ist f\u00fcr viele Anwendungen wichtig, von der Materialwissenschaft bis zur Umweltwissenschaft. In diesem Artikel werfen wir einen Blick auf die verschiedenen Formen, die Kohlenstoff annehmen kann, wie dicht sie sind und wie sich diese Eigenschaften in praktischen Anwendungen niederschlagen.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalts\u00fcbersicht<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Inhaltsverzeichnis umschalten\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Umschalten auf<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#What_Is_Density\" >Was ist Dichte?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Density_of_Carbon_A_Brief_Overview\" >Die Dichte von Kohlenstoff: Ein kurzer \u00dcberblick<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Different_Forms_of_Carbon_and_Their_Densities\" >Verschiedene Formen von Kohlenstoff und ihre Dichten<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Graphite\" >Graphit<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Diamond\" >Diamant<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Amorphous_Carbon\" >Amorpher Kohlenstoff<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Density_of_Carbon_Steel_The_Impact_on_Material_Properties\" >Die Dichte von Kohlenstoffstahl: Der Einfluss auf die Materialeigenschaften<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Applications_of_Carbon_Density\" >Anwendungen von Carbon Density<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Applications_of_Carbon_Fiber\" >Anwendungen von Carbonfaser<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Applications_of_Graphite\" >Anwendungen von Graphit<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Carbon-Carbon_Composites_Applications\" >Kohlenstoff-Kohlenstoff-Verbundwerkstoffe Anwendungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Properties_Applications_of_Amorphous_Carbon\" >Eigenschaften und Anwendungen von amorphem Kohlenstoff<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/#Conclusion\" >Schlussfolgerung<\/a><\/li><\/ul><\/nav><\/div>\n\n<h2><span class=\"ez-toc-section\" id=\"What_Is_Density\"><\/span>Was ist Dichte?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Dichte ist die Masse geteilt durch das Volumen und wird mathematisch ausgedr\u00fcckt als:<\/p>\n<p>Dichte=Masse\/Volumen<\/p>\n<p>Grunds\u00e4tzlich beschreibt die Dichte, wie viel Materie in einem bestimmten Raum zusammengepresst ist. Bei einem Objekt mit hoher Dichte ist die Masse des Materials in ein kleineres Volumen gepackt. Eine geringe Dichte bedeutet, dass das Material verteilt ist. Die Materialdichte desselben Gegenstands hat also ein unterschiedliches Gewicht, eine andere Reaktion in der Umgebung und eine andere Anwendung.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Density_of_Carbon_A_Brief_Overview\"><\/span>Die Dichte von Kohlenstoff: Ein kurzer \u00dcberblick<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Dichte dieser Kohlenstoffvertreter ist sehr unterschiedlich. Verschiedene Anwendungen erfordern unterschiedliche Dichten, je nachdem, wie sich der Kohlenstoff verhalten und wie er verwendet werden soll. Die Gr\u00f6\u00dfe der einzelnen Kohlenstoffatome im Vergleich zu denen von Metallen und die Dichte einer Reihe verschiedener Arten von Kohlenstoff. Insbesondere die Tatsache, dass Graphit, Diamant und amorpher Kohlenstoff ein so unterschiedliches Gewicht haben, erkl\u00e4rt, warum Kohlenstoff ein so \"vielseitiges\" Element ist.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Different_Forms_of_Carbon_and_Their_Densities\"><\/span>Verschiedene Formen von Kohlenstoff und ihre Dichten<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Kohlenstoff kommt in verschiedenen Formen vor, die jeweils eine besondere atomare Struktur und physikalische Eigenschaften aufweisen. Untersuchen wir drei bekannte Arten von Kohlenstoff: Graphit, Diamant und amorpher Kohlenstoff.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Graphite\"><\/span>Graphit<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Sein atomarer Aufbau ist ein Schichtaufbau, bei dem die Kohlenstoffatome in flachen Ebenen gebunden sind. Diese Ebenen k\u00f6nnen leicht aneinander vorbeigleiten, was dem Graphit seine schmierende Eigenschaft verleiht. Es ist leicht und l\u00e4sst sich gut formen, da Graphit eine vergleichsweise geringe Dichte von 2,267 g\/cm3 hat. Dies ist ein Grund daf\u00fcr, dass Graphit in den Minen von Bleistiften und als Schmiermittel in einigen industriellen Anwendungen verwendet wird.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Diamond\"><\/span>Diamant<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Eine weitere Variante des Kohlenstoffs, der Diamant, ist f\u00fcr seine H\u00e4rte und Brillanz bekannt. Bei Diamant sind die Kohlenstoffatome in einer dreidimensionalen Anordnung miteinander verbunden, was zu einem sehr starren und kompakten Material f\u00fchrt. Diamant hat eine Dichte von 3,515 g\/cm3, die deutlich h\u00f6her ist als die von Graphit. Diese Dichte ist einer der Gr\u00fcnde daf\u00fcr, dass Diamant das h\u00e4rteste bekannte nat\u00fcrliche Material ist, das sich zum Schneiden, Bohren und f\u00fcr hochpr\u00e4zise Anwendungen eignet.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Amorphous_Carbon\"><\/span>Amorpher Kohlenstoff<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Amorpher Kohlenstoff ist ein Sammelbegriff f\u00fcr Kohlenstoff, der keine geordnete Anordnung auf einer langreichweitigen Skala aufweist (z. B. Graphit oder Diamant). Er tritt h\u00e4ufig in Form von Ru\u00df, Holzkohle und Ru\u00df auf. Amorpher Kohlenstoff hat eine geringere Dichte als Diamant, ist aber in den meisten F\u00e4llen dichter als Graphit. Seine Dichte variiert je nach Form, liegt aber normalerweise zwischen 1,5 und 2,0 g\/cm3.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-7643  aligncenter\" src=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon.jpg\" alt=\"Dichte von Kohlenstoff\" width=\"483\" height=\"321\" srcset=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon.jpg 1024w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon-300x199.jpg 300w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon-768x510.jpg 768w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon-18x12.jpg 18w, https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon-600x398.jpg 600w\" sizes=\"(max-width: 483px) 100vw, 483px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Density_of_Carbon_Steel_The_Impact_on_Material_Properties\"><\/span>Die Dichte von Kohlenstoffstahl: Der Einfluss auf die Materialeigenschaften<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Kohlenstoffstahl ist ein vielseitiges Material, das im Bauwesen, in der Fertigung und im Maschinenbau weit verbreitet ist. Seine Festigkeit, sein Gewicht und andere mechanische Eigenschaften werden durch seine Dichte beeinflusst. Sehen wir uns die Dichte von Kohlenstoffstahl und ihre Auswirkungen auf die Leistung im Detail an.<\/p>\n<p><strong>Kohlenstoffstahl Dichte kg\/m3<\/strong><\/p>\n<p>Die Dichte von Kohlenstoffstahl schwankt zwischen 7.850 kg\/m3 und 8.050 kg\/m3. Je nach Legierungszusammensetzung und Kohlenstoffgehalt des Stahls kann die Dichte leicht variieren. Ein h\u00f6herer Kohlenstoffgehalt f\u00fchrt zu einer h\u00f6heren Festigkeit und H\u00e4rte, aber zu einer geringeren Duktilit\u00e4t.<\/p>\n<p><strong>Dichte f\u00fcr Kohlenstoffstahl lb\/in3<\/strong><\/p>\n<p>In z\u00f6lligen Einheiten hat Kohlenstoffstahl einen Wert von etwa 0,284 lb\/in3. Dieser Wert gibt den Ingenieuren die M\u00f6glichkeit zu entscheiden, wie sie sonst mit Kohlenstoffstahl arbeiten k\u00f6nnen, wenn sie in Systemen arbeiten, in denen imperiale Ma\u00dfe verwendet werden.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Applications_of_Carbon_Density\"><\/span>Anwendungen von Carbon Density<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Dichte von Kohlenstoff ist eine der wichtigsten Determinanten f\u00fcr seinen Nutzen in zahlreichen Anwendungen. Wenn man wei\u00df, wie sich Kohlenstoff in verschiedenen Anordnungen verh\u00e4lt, kann die Industrie das geeignete Material f\u00fcr die jeweilige Aufgabe ausw\u00e4hlen und so Effizienz und Leistung verbessern.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Applications_of_Carbon_Fiber\"><\/span>Anwendungen von Carbonfaser<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Es handelt sich um eine Familie von Materialien, die aus sehr d\u00fcnnen Str\u00e4ngen von Kohlenstoffatomen bestehen, die in einer kristallinen Struktur miteinander verbunden sind. Sie haben eine geringe Dichte (1,6 g\/cm3) und ein hervorragendes Verh\u00e4ltnis von Festigkeit zu Gewicht, was sie insbesondere f\u00fcr die Luft- und Raumfahrt- sowie die Automobilindustrie ideal macht. Heute werden Kohlenstofffasern in der Luft- und Raumfahrt, im Automobilbau, in Sportger\u00e4ten und sogar in hochwertigen Fahrr\u00e4dern eingesetzt.<\/p>\n<p><a href=\"https:\/\/jinsuncarbon.com\/de\/produkt\/kohlefaser\/\">Kohlefaser<\/a> hat eine geringe Dichte und ist daher ideal f\u00fcr leichte Teile mit geringem Gewicht. Es wird h\u00e4ufig als Ersatz f\u00fcr Metalle wie Stahl oder Aluminium in Anwendungen eingesetzt, bei denen es auf jedes Gramm Gewicht ankommt, wie bei Rennwagen oder Flugzeugen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Applications_of_Graphite\"><\/span>Anwendungen von Graphit<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Aufgrund seiner geringen Dichte und seiner einzigartigen Struktur wird Graphit in einer Vielzahl von Anwendungen eingesetzt. Diese Eigenschaft f\u00fchrt dazu, dass sie h\u00e4ufig in Batterien sowie in elektrochemischen Zellen und Elektroden verwendet werden. In der Industrie, z. B. in der Fertigung und im Maschinenbau, werden die Schmiereigenschaften von Graphit als Trockenschmiermittel genutzt. Neben dem Einsatz in der Stahlherstellung wird Graphit auch bei der Produktion von Bleistiften, Batterien und industriellen Hochtemperaturprozessen verwendet.<\/p>\n<p>Da Graphit ein Feststoff mit geringer Dichte ist, l\u00e4sst er sich leicht transportieren und sowohl f\u00fcr kommerzielle Gro\u00dfanwendungen als auch f\u00fcr kleinere, schnellere Verbraucheranwendungen einsetzen.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Carbon-Carbon_Composites_Applications\"><\/span>Kohlenstoff-Kohlenstoff-Verbundwerkstoffe Anwendungen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><a href=\"https:\/\/jinsuncarbon.com\/de\/produkt\/kohlenstoff-kohlenstoff-verbundstoff\/\">Kohlenstoff-Kohlenstoff-Verbundwerkstoffe<\/a> bestehen aus Kohlenstofffasern in Kombination mit einer Kohlenstoffmatrix. Diese Verbundwerkstoffe bieten eine einzigartige Kombination aus hoher Festigkeit und geringer Dichte und eignen sich f\u00fcr Hochleistungsanwendungen, insbesondere unter extremer Hitzeeinwirkung.<\/p>\n<p>Kohlenstoff-Kohlenstoff-Verbundwerkstoffe werden in Teilen der Luft- und Raumfahrt eingesetzt, wie <a href=\"https:\/\/en.wikipedia.org\/wiki\/Rocket_engine_nozzle\" target=\"_blank\" rel=\"noopener\">Raketend\u00fcsen<\/a>und in Bremssystemen von Hochgeschwindigkeitsz\u00fcgen und -fahrzeugen, da sie eine hohe Dichte vertragen. Sie sind auch extrem widerstandsf\u00e4hig gegen hohe Temperaturen, ohne ihre strukturelle Integrit\u00e4t zu verlieren, was sie in der Luft- und Raumfahrt- sowie in der Automobilindustrie sehr begehrt macht.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Properties_Applications_of_Amorphous_Carbon\"><\/span>Eigenschaften und Anwendungen von amorphem Kohlenstoff<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><a href=\"https:\/\/en.wikipedia.org\/wiki\/Amorphous_carbon#:~:text=Amorphous%20carbon%20is%20free%2C%20reactive,range%20order%20can%20be%20observed.\" target=\"_blank\" rel=\"noopener\">Amorpher Kohlenstoff<\/a> hat mehrere Verwendungszwecke, von denen die meisten auf seine variable Dichte zur\u00fcckzuf\u00fchren sind. Amorpher Kohlenstoff wird haupts\u00e4chlich zur Herstellung von Ru\u00df verwendet, einem Material, das in der Gummiindustrie, insbesondere in Reifen, eingesetzt wird. Au\u00dferdem wird amorpher Kohlenstoff in Beschichtungen f\u00fcr Werkzeuge und Maschinen verwendet, um deren Verschlei\u00dffestigkeit zu verbessern.<\/p>\n<p>Ein weiterer Anwendungsbereich f\u00fcr amorphen Kohlenstoff ist aufgrund seiner Vielseitigkeit die Energiespeicherung, wo er f\u00fcr die Herstellung von Superkondensatoren und Batterien unerl\u00e4sslich ist.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Schlussfolgerung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Die Eigenschaften und Anwendungen von Kohlenstoff werden in hohem Ma\u00dfe von der Dichte des Kohlenstoffs beeinflusst. Jede dieser vielf\u00e4ltigen Formen hat ihre eigene Dichte, ob es sich nun um Graphit, Diamant, amorphen Kohlenstoff oder Kohlenstoffstahl handelt, was ihr in verschiedenen Industriezweigen ihre eigenen Vorteile verleiht. Ganz gleich, ob es sich um das geringe Gewicht von Kohlenstofffasern oder die hohe Hitzebest\u00e4ndigkeit von Kohlenstoff-Kohlenstoff-Verbundwerkstoffen handelt - wenn Sie die Dichte von Kohlenstoff kennen, werden Sie feststellen, wie wichtig dieses Atom sein kann.<\/p>\n<p class=\"ql-align-justify\">","protected":false},"excerpt":{"rendered":"<p>Carbon is one of the basic building block of our universe, with every science around it being very modern in organic life, industrial applications, and materials science. Density, the mass of carbon atoms per unit volume, is one of the key properties of carbon. The density of carbon is important for many applications, from materials [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carbon-graphite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v19.2.1 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Density of Carbon - A Quick Overview | Jinsun Carbon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Density of Carbon - A Quick Overview\" \/>\n<meta property=\"og:description\" content=\"Carbon is one of the basic building block of our universe, with every science around it being very modern in organic life, industrial applications, and materials science. Density, the mass of carbon atoms per unit volume, is one of the key properties of carbon. The density of carbon is important for many applications, from materials [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/\" \/>\n<meta property=\"og:site_name\" content=\"Jinsun Carbon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-17T01:29:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-17T01:44:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jinsuncarbon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jinsuncarbon_\" \/>\n<meta name=\"twitter:site\" content=\"@jinsuncarbon_\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"jinsuncarbon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/\"},\"author\":{\"name\":\"jinsuncarbon\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#\\\/schema\\\/person\\\/6d19b66d2a95154652ba3b86492d27b5\"},\"headline\":\"Density of Carbon &#8211; A Quick Overview\",\"datePublished\":\"2025-02-17T01:29:24+00:00\",\"dateModified\":\"2025-02-17T01:44:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/\"},\"wordCount\":1106,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/density-of-carbon.jpg\",\"articleSection\":[\"Carbon Graphite Products\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/\",\"name\":\"Density of Carbon - A Quick Overview | Jinsun Carbon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/density-of-carbon.jpg\",\"datePublished\":\"2025-02-17T01:29:24+00:00\",\"dateModified\":\"2025-02-17T01:44:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/density-of-carbon.jpg\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/density-of-carbon.jpg\",\"width\":1024,\"height\":680,\"caption\":\"density of carbon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/density-of-carbon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jinsuncarbon.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Density of Carbon &#8211; A Quick Overview\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#website\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"name\":\"Jinsun Carbon\",\"description\":\"We are the successful graphite electrode manufacturer in China\",\"publisher\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jinsuncarbon.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#organization\",\"name\":\"Jinsun Carbon\",\"alternateName\":\"Jinsun Carbon\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"contentUrl\":\"https:\\\/\\\/jinsuncarbon.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/LOGO-1.png\",\"width\":207,\"height\":80,\"caption\":\"Jinsun Carbon\"},\"image\":{\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Graphite-Electrode-109336238661595\",\"https:\\\/\\\/x.com\\\/jinsuncarbon_\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jinsungraphite\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCysDNyvyR5-3cCWEmpkVC0g\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jinsuncarbon.com\\\/#\\\/schema\\\/person\\\/6d19b66d2a95154652ba3b86492d27b5\",\"name\":\"jinsuncarbon\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g\",\"caption\":\"jinsuncarbon\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die Dichte von Kohlenstoff - ein kurzer \u00dcberblick | Jinsun Carbon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/","og_locale":"de_DE","og_type":"article","og_title":"Density of Carbon - A Quick Overview","og_description":"Carbon is one of the basic building block of our universe, with every science around it being very modern in organic life, industrial applications, and materials science. Density, the mass of carbon atoms per unit volume, is one of the key properties of carbon. The density of carbon is important for many applications, from materials [&hellip;]","og_url":"https:\/\/jinsuncarbon.com\/de\/dichte-von-kohlenstoff\/","og_site_name":"Jinsun Carbon","article_publisher":"https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","article_published_time":"2025-02-17T01:29:24+00:00","article_modified_time":"2025-02-17T01:44:34+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon.jpg","type":"image\/jpeg"}],"author":"jinsuncarbon","twitter_card":"summary_large_image","twitter_creator":"@jinsuncarbon_","twitter_site":"@jinsuncarbon_","twitter_misc":{"Verfasst von":"jinsuncarbon","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/#article","isPartOf":{"@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/"},"author":{"name":"jinsuncarbon","@id":"https:\/\/jinsuncarbon.com\/#\/schema\/person\/6d19b66d2a95154652ba3b86492d27b5"},"headline":"Density of Carbon &#8211; A Quick Overview","datePublished":"2025-02-17T01:29:24+00:00","dateModified":"2025-02-17T01:44:34+00:00","mainEntityOfPage":{"@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/"},"wordCount":1106,"commentCount":0,"publisher":{"@id":"https:\/\/jinsuncarbon.com\/#organization"},"image":{"@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/#primaryimage"},"thumbnailUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon.jpg","articleSection":["Carbon Graphite Products"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jinsuncarbon.com\/density-of-carbon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/","url":"https:\/\/jinsuncarbon.com\/density-of-carbon\/","name":"Die Dichte von Kohlenstoff - ein kurzer \u00dcberblick | Jinsun Carbon","isPartOf":{"@id":"https:\/\/jinsuncarbon.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/#primaryimage"},"image":{"@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/#primaryimage"},"thumbnailUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon.jpg","datePublished":"2025-02-17T01:29:24+00:00","dateModified":"2025-02-17T01:44:34+00:00","breadcrumb":{"@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jinsuncarbon.com\/density-of-carbon\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/#primaryimage","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon.jpg","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2025\/02\/density-of-carbon.jpg","width":1024,"height":680,"caption":"density of carbon"},{"@type":"BreadcrumbList","@id":"https:\/\/jinsuncarbon.com\/density-of-carbon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jinsuncarbon.com\/"},{"@type":"ListItem","position":2,"name":"Density of Carbon &#8211; A Quick Overview"}]},{"@type":"WebSite","@id":"https:\/\/jinsuncarbon.com\/#website","url":"https:\/\/jinsuncarbon.com\/","name":"Jinsun Kohlenstoff","description":"Wir sind der erfolgreiche Hersteller von Graphitelektroden in China","publisher":{"@id":"https:\/\/jinsuncarbon.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jinsuncarbon.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/jinsuncarbon.com\/#organization","name":"Jinsun Kohlenstoff","alternateName":"Jinsun Carbon","url":"https:\/\/jinsuncarbon.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/jinsuncarbon.com\/#\/schema\/logo\/image\/","url":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","contentUrl":"https:\/\/jinsuncarbon.com\/wp-content\/uploads\/2022\/12\/LOGO-1.png","width":207,"height":80,"caption":"Jinsun Carbon"},"image":{"@id":"https:\/\/jinsuncarbon.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Graphite-Electrode-109336238661595","https:\/\/x.com\/jinsuncarbon_","https:\/\/www.linkedin.com\/in\/jinsungraphite","https:\/\/www.youtube.com\/channel\/UCysDNyvyR5-3cCWEmpkVC0g"]},{"@type":"Person","@id":"https:\/\/jinsuncarbon.com\/#\/schema\/person\/6d19b66d2a95154652ba3b86492d27b5","name":"jinsuncarbon","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7abf5819913301446abda76750263066aa3a1d311fa4df65b39e847239480105?s=96&d=mm&r=g","caption":"jinsuncarbon"}}]}},"_links":{"self":[{"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/posts\/7642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/comments?post=7642"}],"version-history":[{"count":4,"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/posts\/7642\/revisions"}],"predecessor-version":[{"id":7645,"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/posts\/7642\/revisions\/7645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/media\/7643"}],"wp:attachment":[{"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/media?parent=7642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/categories?post=7642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jinsuncarbon.com\/de\/wp-json\/wp\/v2\/tags?post=7642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}